


{"id":9849,"date":"2016-11-21T09:49:51","date_gmt":"2016-11-21T09:49:51","guid":{"rendered":"http:\/\/www.unirufa.it\/?p=9459"},"modified":"2020-08-06T11:58:33","modified_gmt":"2020-08-06T09:58:33","slug":"rufa-contest-karim-rashid-colorato-roma","status":"publish","type":"post","link":"https:\/\/www.unirufa.it\/es\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/","title":{"rendered":"RUFA Contest, Karim Rashid ha colorato Roma"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-es\">Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en <a href=\"https:\/\/www.unirufa.it\/it\/wp-json\/wp\/v2\/posts\/9849\" class=\"qtranxs-available-language-link qtranxs-available-language-link-it\" title=\"IT\">IT<\/a> y <a href=\"https:\/\/www.unirufa.it\/en\/wp-json\/wp\/v2\/posts\/9849\" class=\"qtranxs-available-language-link qtranxs-available-language-link-en\" title=\"EN\">EN<\/a>.<\/p><h3>Il designer canadese si \u00e8 raccontato al pubblico e ha scelto RICCARDO QUATTROCIOCCHE come vincitore del RUFA Contest<\/h3>\n<p>Venerd\u00ec 18 novembre all\u2019Auditorium del Massimo \u00e8 andato in scena un RUFA Contest memorabile. Questo anno accademico ha avuto una partenza in grande stile, con l\u2019Accademia che ha presentato alla citt\u00e0 di Roma il designer canadese, eccentrico e bizzarro come non mai, il quale ha ripagato tutti con una performance collettiva iper-tecnologica per introdurre il tema scelto per questa edizione del concorso: How deep are your roots? Represent the courage to change (Quanto sono profonde le tue radici? Racconta il coraggio di cambiare). \u00abHo vissuto da piccolo a Roma, Londra, Toronto, Milano, New York: queste sono le mie radici\u00bb, cos\u00ec ha cominciato Rashid il suo spettacolo. Brillante e visionario, conosciuto ai pi\u00f9 per il suo tocco cromatico inconfondibile, quello del rosa, per il RUFA contest si \u00e8 presentato invece con un outfit total white, portando subito lo spettatore al centro della sua ricerca: \u00abSiamo nell\u2019epoca digitale, viviamo uno scisma tra analogico e digitale. Dobbiamo essere pi\u00f9 coscienti delle potenzialit\u00e0 della tecnologia, perch\u00e9 \u00e8 un\u2019evoluzione organica della natura stessa e arriver\u00e0 tra un nanosecondo. Ma non voglio parlare del futuro, n\u00e9 della nostalgia del passato, tutto quello che possediamo \u00e8 il presente\u00bb.<\/p>\n<p><strong>LO SPETTACOLO <\/strong><br \/>\nEd \u00e8 proprio la tecnologia, per Rashid, la base della creativit\u00e0: \u00abDovete svegliarvi domani mattina e fare qualcosa che nessuna di quelle 7,4 miliardi di persone nel mondo ha mai fatto\u00bb. Una filosofia che il designer ha abbracciato a 360 gradi e che rende le sue creazioni sinonimo di inventiva, estro e tendenza: dall\u2019illuminazione (Artemide o Fabbian), all\u2019arredo (Bonaldo o Vondom), all\u2019hi-tech (Asus o Samsung) fino ai locali (Morimoto a Philadelphia; Hotel Semiramis ad Atene o l\u2019Hotel Nhow a Berlino). Alcuni dei suoi prodotti, come vere e proprie opere d\u2019arte, sono entrati a far parte delle collezioni pi\u00f9 prestigiose del mondo, come il MoMa di New York, o arricchiscono luoghi pubblici di alcune citt\u00e0, come la monumentale decorazione della Stazione metro di Napoli \u201cUniversit\u00e0\u201d.<\/p>\n<p>Scorrendo alcune delle sue pi\u00f9 significative creazioni, Rashid ha condotto lo spettatore all\u2019interno della sua ricerca che ha sovvertito le regole del design con uno stile fatto di linee morbide e curve, rese prevalentemente con l&#8217;utilizzo di materiali come plastica e gomma: \u00abNon credo nella griglia: sono simmetrico, organico, amorfo. Una linea retta non esiste in natura. Perch\u00e9 continuiamo ad andarle contro?\u00bb. Proprio il tema della natura sembra essere un fil rouge nel pensiero di Rashid: \u00abC\u2019\u00e8 un masterplan che ci ha condotto all\u2019epoca digitale per sopravvivere, ci siamo arrivati per salvare la terra. Se vogliamo fare qualcosa di importante per il mondo, dobbiamo lasciare tutto ci\u00f2 che \u00e8 materiale, nell\u2019era digitale tutto \u00e8 dematerializzato. Il superfluo \u00e8 un ostacolo alla vita reale. Questo significa libert\u00e0\u00bb.<\/p>\n<p><strong>IL VINCITORE DEL CONTEST<\/strong><br \/>\nMa Rufa Contest non \u00e8 solo uno spettacolo, \u00e8 anche un momento di riconoscimento importante per gli studenti che frequentano l\u2019Accademia. Come da nome, infatti, si tratta della conclusione di un percorso creativo che ha visto gli alunni Rufa confrontarsi con il tema di quest\u2019anno.<br \/>\nAl termine dello show Rashid ha premiato il vincitore del RUFA Contest 2016, <strong>Riccardo Quattrociocche<\/strong> che ha convinto tutti con il video \u00abGuardarsi\u00bb: \u00ab\u00c8 stato molto difficile scegliere \u2013 ha spiegato il designer \u2013 ma questo video ha toccato il mio cuore. \u00c8 emozionante, potente, durissimo, tutte le emozioni che l\u2019arte dovrebbe regalare\u00bb.<\/p>\n<p><strong>I PREMI SPECIALI<\/strong><br \/>\nQuattrociocche non \u00e8 stato l\u2019unico studente a salire sul palco. Insieme a lui, sono stati premiati altri talentuosi giovani artisti dell\u2019Accademia dai partner del concorso: Sky Arte Hd ha riconosciuto in \u00abContrattempo\u00bb di Elisa Selli un lavoro \u00abdiretto e artisticamente molto equilibrato\u00bb; Mtv ha scelto invece come premio speciale \u00abNow I Am\u00bb di Gabriele Caterini: \u00abUn\u2019opera coraggiosa che incontra i nostri stessi valori\u00bb; Fandango ha selezionato il lavoro di Lorenzo Squarcia, \u00abGoing forward through the past\u00bb: \u00abIl nostro lavoro \u00e8 cercare nuovi talenti, \u00e8 stata dura ma questo progetto si avvicina molto a quello che facciamo noi\u00bb; Olivetti ha fatto ricadere la sua scelta su \u00abIl mio nome \u00e8 Tarek\u00bb, firmato da Claudia Rolando; Roberta Bartolomucci \u00e8 invece il premio speciale Inside Art, con un\u2019installazione da cui emerge un\u2019interpretazione intelligente sul tema del contest. \u00abRadici sociali\u00bb, questo il titolo, \u00e8 un\u2019analisi incentrata sul concetto di memoria e relazioni nell\u2019era dei Social Network; anche Radio Globo ha scelto Lorenzo Squarcia con \u00abGoing forward through the past\u00bb. La menzione speciale della giuria, invece, consegnata dal direttore RUFA Fabio Mongelli, \u00e8 stata data ad Alan Parroni con \u00abAnywhere at home\u00bb: \u00abParroni \u00e8 un vero talento \u2013 ha detto il direttore \u2013 ci ha colpito molto: del resto, chi non amerebbe mettersi in testa un vaso di Pandora e rivivere ricordi in tre dimensioni\u00bb.<\/p>\n<p>Una serata densa di emozioni, all\u2019insegna della conoscenza: il design, grazie a Karim Rashid, \u00e8 diventato pi\u00f9 familiare.","protected":false},"excerpt":{"rendered":"<p>Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Il designer canadese si \u00e8 raccontato al pubblico e ha scelto RICCARDO QUATTROCIOCCHE come vincitore del RUFA Contest Venerd\u00ec 18 novembre all\u2019Auditorium del Massimo \u00e8 andato in scena un RUFA Contest memorabile. Questo anno accademico ha avuto una partenza in grande stile, con l\u2019Accademia che&#8230;  <a class=\"excerpt-read-more\" href=\"https:\/\/www.unirufa.it\/es\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/\" title=\"Read RUFA Contest, Karim Rashid ha colorato Roma\">Find out more<\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"content-type":"","footnotes":""},"categories":[1629,31,939],"tags":[],"class_list":["post-9849","post","type-post","status-publish","format-standard","hentry","category-accademia","category-app-news","category-product-interior-design"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>RUFA Contest, Karim Rashid ha colorato Roma - RUFA - Rome University of Fine Arts<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"RUFA Contest, Karim Rashid ha colorato Roma - RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"og:description\" content=\"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Il designer canadese si \u00e8 raccontato al pubblico e ha scelto RICCARDO QUATTROCIOCCHE come vincitore del RUFA Contest Venerd\u00ec 18 novembre all\u2019Auditorium del Massimo \u00e8 andato in scena un RUFA Contest memorabile. Questo anno accademico ha avuto una partenza in grande stile, con l\u2019Accademia che... Find out more\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/\" \/>\n<meta property=\"og:site_name\" content=\"RUFA - Rome University of Fine Arts\" \/>\n<meta property=\"article:published_time\" content=\"2016-11-21T09:49:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-08-06T09:58:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.unirufa.it\/wp-content\/uploads\/2017\/11\/logo-rufa-2016.png\" \/>\n\t<meta property=\"og:image:width\" content=\"230\" \/>\n\t<meta property=\"og:image:height\" content=\"149\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"rufa\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"rufa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/\",\"url\":\"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/\",\"name\":\"RUFA Contest, Karim Rashid ha colorato Roma - RUFA - Rome University of Fine Arts\",\"isPartOf\":{\"@id\":\"https:\/\/www.unirufa.it\/#website\"},\"datePublished\":\"2016-11-21T09:49:51+00:00\",\"dateModified\":\"2020-08-06T09:58:33+00:00\",\"author\":{\"@id\":\"https:\/\/www.unirufa.it\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.unirufa.it\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"RUFA Contest, Karim Rashid ha colorato Roma\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.unirufa.it\/#website\",\"url\":\"https:\/\/www.unirufa.it\/\",\"name\":\"RUFA - Rome University of Fine Arts\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.unirufa.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.unirufa.it\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917\",\"name\":\"rufa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.unirufa.it\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g\",\"caption\":\"rufa\"},\"url\":\"https:\/\/www.unirufa.it\/es\/author\/rufa\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"RUFA Contest, Karim Rashid ha colorato Roma - RUFA - Rome University of Fine Arts","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/","og_locale":"es_ES","og_type":"article","og_title":"RUFA Contest, Karim Rashid ha colorato Roma - RUFA - Rome University of Fine Arts","og_description":"Disculpa, pero esta entrada est\u00e1 disponible s\u00f3lo en IT y EN.Il designer canadese si \u00e8 raccontato al pubblico e ha scelto RICCARDO QUATTROCIOCCHE come vincitore del RUFA Contest Venerd\u00ec 18 novembre all\u2019Auditorium del Massimo \u00e8 andato in scena un RUFA Contest memorabile. Questo anno accademico ha avuto una partenza in grande stile, con l\u2019Accademia che... Find out more","og_url":"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/","og_site_name":"RUFA - Rome University of Fine Arts","article_published_time":"2016-11-21T09:49:51+00:00","article_modified_time":"2020-08-06T09:58:33+00:00","og_image":[{"width":230,"height":149,"url":"https:\/\/www.unirufa.it\/wp-content\/uploads\/2017\/11\/logo-rufa-2016.png","type":"image\/png"}],"author":"rufa","twitter_misc":{"Escrito por":"rufa","Tiempo de lectura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/","url":"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/","name":"RUFA Contest, Karim Rashid ha colorato Roma - RUFA - Rome University of Fine Arts","isPartOf":{"@id":"https:\/\/www.unirufa.it\/#website"},"datePublished":"2016-11-21T09:49:51+00:00","dateModified":"2020-08-06T09:58:33+00:00","author":{"@id":"https:\/\/www.unirufa.it\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917"},"breadcrumb":{"@id":"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.unirufa.it\/en\/2016\/11\/21\/rufa-contest-karim-rashid-colorato-roma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.unirufa.it\/"},{"@type":"ListItem","position":2,"name":"RUFA Contest, Karim Rashid ha colorato Roma"}]},{"@type":"WebSite","@id":"https:\/\/www.unirufa.it\/#website","url":"https:\/\/www.unirufa.it\/","name":"RUFA - Rome University of Fine Arts","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.unirufa.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.unirufa.it\/#\/schema\/person\/df501afc19e72ccaeeaaec268b0c5917","name":"rufa","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.unirufa.it\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7f7ea0eea9301536a533fa1d7ea507b9?s=96&d=mm&r=g","caption":"rufa"},"url":"https:\/\/www.unirufa.it\/es\/author\/rufa\/"}]}},"_links":{"self":[{"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/posts\/9849","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/comments?post=9849"}],"version-history":[{"count":2,"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/posts\/9849\/revisions"}],"predecessor-version":[{"id":30979,"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/posts\/9849\/revisions\/30979"}],"wp:attachment":[{"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/media?parent=9849"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/categories?post=9849"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.unirufa.it\/es\/wp-json\/wp\/v2\/tags?post=9849"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}